
{"id":97,"count":4,"description":"","link":"https:\/\/support.wewalk.io\/en\/docs-category\/obstacle-detection-using-wewalk-v2-user-guide\/","name":"Obstacle Detection","slug":"obstacle-detection-using-wewalk-v2-user-guide","taxonomy":"doc_category","parent":95,"meta":{"doc_category_image-id":""},"lang":"en","doc_category_order":6,"thumbnail":null,"handbookthumbnail":null,"subcategories_count":0,"total_docs_count":4,"last_updated_time":"September 2, 2026","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Obstacle Detection Archives - WeWalk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/support.wewalk.io\/en\/docs-category\/obstacle-detection-using-wewalk-v2-user-guide\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obstacle Detection Archives - WeWalk\" \/>\n<meta property=\"og:url\" content=\"https:\/\/support.wewalk.io\/en\/docs-category\/obstacle-detection-using-wewalk-v2-user-guide\/\" \/>\n<meta property=\"og:site_name\" content=\"WeWalk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/support.wewalk.io\\\/en\\\/docs-category\\\/obstacle-detection-using-wewalk-v2-user-guide\\\/\",\"url\":\"https:\\\/\\\/support.wewalk.io\\\/en\\\/docs-category\\\/obstacle-detection-using-wewalk-v2-user-guide\\\/\",\"name\":\"Obstacle Detection Archives - WeWalk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/support.wewalk.io\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/support.wewalk.io\\\/en\\\/docs-category\\\/obstacle-detection-using-wewalk-v2-user-guide\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/support.wewalk.io\\\/en\\\/docs-category\\\/obstacle-detection-using-wewalk-v2-user-guide\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/support.wewalk.io\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Smart Cane 2 User Guide\",\"item\":\"https:\\\/\\\/support.wewalk.io\\\/en\\\/docs-category\\\/v2-user-guide\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Using WeWALK\",\"item\":\"https:\\\/\\\/support.wewalk.io\\\/en\\\/docs-category\\\/using-wewalk-v2-user-guide\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Obstacle Detection\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/support.wewalk.io\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/support.wewalk.io\\\/en\\\/\",\"name\":\"WeWalk\",\"description\":\"Support\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/support.wewalk.io\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obstacle Detection Archives - WeWalk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/support.wewalk.io\/en\/docs-category\/obstacle-detection-using-wewalk-v2-user-guide\/","og_locale":"en_US","og_type":"article","og_title":"Obstacle Detection Archives - WeWalk","og_url":"https:\/\/support.wewalk.io\/en\/docs-category\/obstacle-detection-using-wewalk-v2-user-guide\/","og_site_name":"WeWalk","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/support.wewalk.io\/en\/docs-category\/obstacle-detection-using-wewalk-v2-user-guide\/","url":"https:\/\/support.wewalk.io\/en\/docs-category\/obstacle-detection-using-wewalk-v2-user-guide\/","name":"Obstacle Detection Archives - WeWalk","isPartOf":{"@id":"https:\/\/support.wewalk.io\/en\/#website"},"breadcrumb":{"@id":"https:\/\/support.wewalk.io\/en\/docs-category\/obstacle-detection-using-wewalk-v2-user-guide\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/support.wewalk.io\/en\/docs-category\/obstacle-detection-using-wewalk-v2-user-guide\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/support.wewalk.io\/en\/"},{"@type":"ListItem","position":2,"name":"Smart Cane 2 User Guide","item":"https:\/\/support.wewalk.io\/en\/docs-category\/v2-user-guide\/"},{"@type":"ListItem","position":3,"name":"Using WeWALK","item":"https:\/\/support.wewalk.io\/en\/docs-category\/using-wewalk-v2-user-guide\/"},{"@type":"ListItem","position":4,"name":"Obstacle Detection"}]},{"@type":"WebSite","@id":"https:\/\/support.wewalk.io\/en\/#website","url":"https:\/\/support.wewalk.io\/en\/","name":"WeWalk","description":"Support","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/support.wewalk.io\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/support.wewalk.io\/en\/wp-json\/wp\/v2\/doc_category\/97","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/support.wewalk.io\/en\/wp-json\/wp\/v2\/doc_category"}],"about":[{"href":"https:\/\/support.wewalk.io\/en\/wp-json\/wp\/v2\/taxonomies\/doc_category"}],"up":[{"embeddable":true,"href":"https:\/\/support.wewalk.io\/en\/wp-json\/wp\/v2\/doc_category\/95"}],"wp:post_type":[{"href":"https:\/\/support.wewalk.io\/en\/wp-json\/wp\/v2\/docs?doc_category=97"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}