
{"id":2781,"date":"2024-04-25T20:30:00","date_gmt":"2024-04-25T17:30:00","guid":{"rendered":"https:\/\/support.wewalk.io\/article\/cose-la-funzione-trasporto\/"},"modified":"2026-06-10T16:03:08","modified_gmt":"2026-06-10T13:03:08","password":"","slug":"cose-la-funzione-trasporto","status":"publish","type":"docs","link":"https:\/\/support.wewalk.io\/it\/article\/cose-la-funzione-trasporto\/","title":{"rendered":"Cos\u2019\u00e8 la Funzione Trasporto?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La funzione \u201cTrasporto\u201d \u00e8 il terzo pulsante nella schermata Home dell\u2019app WeWALK. Questa funzione consente di esplorare tutte le fermate del trasporto pubblico nelle vicinanze. <\/p>\n\n<p class=\"wp-block-paragraph\">Dopo aver toccato la scheda \u201cTrasporto\u201d, verranno mostrate tutte le fermate degli autobus nelle vicinanze e la distanza da ciascuna di esse. Toccando una fermata, \u00e8 possibile visualizzare le linee di trasporto che passano e si fermano in quel punto selezionando \u201cLinee Trasporto\u201d sullo schermo. Da qui \u00e8 possibile anche ottenere indicazioni per raggiungere la fermata toccando \u201cVai l\u00ec\u201d e salvare la posizione della fermata tra i luoghi salvati toccando \u201cSalva Posizione\u201d. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La funzione \u201cTrasporto\u201d \u00e8 il terzo pulsante nella schermata Home dell\u2019app WeWALK. Questa funzione consente di esplorare tutte le fermate del trasporto pubblico nelle vicinanze. Dopo aver toccato la scheda \u201cTrasporto\u201d, verranno mostrate tutte le fermate degli autobus nelle vicinanze e la distanza da ciascuna di esse. Toccando una fermata, \u00e8 possibile visualizzare le linee [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"doc_category":[215],"doc_tag":[],"class_list":["post-2781","docs","type-docs","status-publish","hentry","doc_category-la-funzione-trasporto"],"year_month":"2026-09","word_count":95,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"Ece Celebi","author_nicename":"ece","author_url":"https:\/\/support.wewalk.io\/it\/author\/ece\/"},"doc_category_info":[{"term_name":"La Funzione Trasporto","term_url":"https:\/\/support.wewalk.io\/it\/art-cat\/la-funzione-trasporto\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cos\u2019\u00e8 la Funzione Trasporto? - WeWalk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/support.wewalk.io\/it\/article\/cose-la-funzione-trasporto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cos\u2019\u00e8 la Funzione Trasporto? - WeWalk\" \/>\n<meta property=\"og:description\" content=\"La funzione \u201cTrasporto\u201d \u00e8 il terzo pulsante nella schermata Home dell\u2019app WeWALK. Questa funzione consente di esplorare tutte le fermate del trasporto pubblico nelle vicinanze. Dopo aver toccato la scheda \u201cTrasporto\u201d, verranno mostrate tutte le fermate degli autobus nelle vicinanze e la distanza da ciascuna di esse. Toccando una fermata, \u00e8 possibile visualizzare le linee [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/support.wewalk.io\/it\/article\/cose-la-funzione-trasporto\/\" \/>\n<meta property=\"og:site_name\" content=\"WeWalk\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-10T13:03:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/article\\\/cose-la-funzione-trasporto\\\/\",\"url\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/article\\\/cose-la-funzione-trasporto\\\/\",\"name\":\"Cos\u2019\u00e8 la Funzione Trasporto? - WeWalk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/#website\"},\"datePublished\":\"2024-04-25T17:30:00+00:00\",\"dateModified\":\"2026-06-10T13:03:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/article\\\/cose-la-funzione-trasporto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/support.wewalk.io\\\/it\\\/article\\\/cose-la-funzione-trasporto\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/article\\\/cose-la-funzione-trasporto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articoli\",\"item\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/docs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cos\u2019\u00e8 la Funzione Trasporto?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/\",\"name\":\"WeWalk\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cos\u2019\u00e8 la Funzione Trasporto? - WeWalk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/support.wewalk.io\/it\/article\/cose-la-funzione-trasporto\/","og_locale":"it_IT","og_type":"article","og_title":"Cos\u2019\u00e8 la Funzione Trasporto? - WeWalk","og_description":"La funzione \u201cTrasporto\u201d \u00e8 il terzo pulsante nella schermata Home dell\u2019app WeWALK. Questa funzione consente di esplorare tutte le fermate del trasporto pubblico nelle vicinanze. Dopo aver toccato la scheda \u201cTrasporto\u201d, verranno mostrate tutte le fermate degli autobus nelle vicinanze e la distanza da ciascuna di esse. Toccando una fermata, \u00e8 possibile visualizzare le linee [&hellip;]","og_url":"https:\/\/support.wewalk.io\/it\/article\/cose-la-funzione-trasporto\/","og_site_name":"WeWalk","article_modified_time":"2026-06-10T13:03:08+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/support.wewalk.io\/it\/article\/cose-la-funzione-trasporto\/","url":"https:\/\/support.wewalk.io\/it\/article\/cose-la-funzione-trasporto\/","name":"Cos\u2019\u00e8 la Funzione Trasporto? - WeWalk","isPartOf":{"@id":"https:\/\/support.wewalk.io\/it\/#website"},"datePublished":"2024-04-25T17:30:00+00:00","dateModified":"2026-06-10T13:03:08+00:00","breadcrumb":{"@id":"https:\/\/support.wewalk.io\/it\/article\/cose-la-funzione-trasporto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/support.wewalk.io\/it\/article\/cose-la-funzione-trasporto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/support.wewalk.io\/it\/article\/cose-la-funzione-trasporto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/support.wewalk.io\/it\/"},{"@type":"ListItem","position":2,"name":"Articoli","item":"https:\/\/support.wewalk.io\/it\/docs\/"},{"@type":"ListItem","position":3,"name":"Cos\u2019\u00e8 la Funzione Trasporto?"}]},{"@type":"WebSite","@id":"https:\/\/support.wewalk.io\/it\/#website","url":"https:\/\/support.wewalk.io\/it\/","name":"WeWalk","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/support.wewalk.io\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/docs\/2781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/comments?post=2781"}],"version-history":[{"count":1,"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/docs\/2781\/revisions"}],"predecessor-version":[{"id":2782,"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/docs\/2781\/revisions\/2782"}],"wp:attachment":[{"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/media?parent=2781"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/doc_category?post=2781"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/doc_tag?post=2781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}