
{"id":2789,"date":"2024-04-25T20:30:00","date_gmt":"2024-04-25T17:30:00","guid":{"rendered":"https:\/\/support.wewalk.io\/article\/personalizzazione-dellapp-per-utenti-ipovedenti\/"},"modified":"2026-06-10T19:15:57","modified_gmt":"2026-06-10T16:15:57","password":"","slug":"personalizzazione-dellapp-per-utenti-ipovedenti","status":"publish","type":"docs","link":"https:\/\/support.wewalk.io\/it\/article\/personalizzazione-dellapp-per-utenti-ipovedenti\/","title":{"rendered":"Personalizzazione dell\u2019App per Utenti Ipovedenti"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L\u2019app WeWALK \u00e8 progettata sia per persone ipovedenti sia per persone non vedenti. Per questo motivo, l\u2019app consente di modificare le impostazioni visive per migliorare l\u2019accessibilit\u00e0. Seguire i passaggi seguenti per personalizzare l\u2019app in base alle esigenze degli utenti ipovedenti: <\/p>\n\n<p class=\"wp-block-paragraph\">1. Aprire la sezione \u201cIl Mio Account\u201d \u2013 Toccare il pulsante \u201cIl Mio Account\u201d, situato in basso a destra dello schermo. <\/p>\n\n<p class=\"wp-block-paragraph\">2. Andare a Preferenze \u2013 Selezionare \u201cPreferenze\u201d. <\/p>\n\n<p class=\"wp-block-paragraph\">3. Selezionare \u201cAltre Preferenze\u201d \u2013 Toccare il terzo pulsante, \u201cAltre Preferenze\u201d. <\/p>\n\n<p class=\"wp-block-paragraph\">4. Toccare \u201cPreferenze Visive\u201d. <\/p>\n\n<p class=\"wp-block-paragraph\">5. Regolare le impostazioni visive \u2013 Per impostazione predefinita, l\u2019app usa testo nero su sfondo bianco. Tuttavia, \u00e8 possibile passare a testo bianco su sfondo nero oppure a testo giallo su sfondo nero. \u00c8 anche possibile personalizzare la dimensione del testo in base alle proprie esigenze. <\/p>\n\n<p class=\"wp-block-paragraph\">6. Applicare le modifiche \u2013 Dopo aver selezionato le impostazioni preferite, toccare il pulsante \u201cApplica\u201d per salvare le modifiche. <\/p>\n\n<p class=\"wp-block-paragraph\">Queste regolazioni garantiscono un\u2019esperienza pi\u00f9 accessibile e confortevole per gli utenti con problemi visivi. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019app WeWALK \u00e8 progettata sia per persone ipovedenti sia per persone non vedenti. Per questo motivo, l\u2019app consente di modificare le impostazioni visive per migliorare l\u2019accessibilit\u00e0. Seguire i passaggi seguenti per personalizzare l\u2019app in base alle esigenze degli utenti ipovedenti: 1. Aprire la sezione \u201cIl Mio Account\u201d \u2013 Toccare il pulsante \u201cIl Mio Account\u201d, situato [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"doc_category":[217],"doc_tag":[],"class_list":["post-2789","docs","type-docs","status-publish","hentry","doc_category-preferenze"],"year_month":"2026-09","word_count":154,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"Ece Celebi","author_nicename":"ece","author_url":"https:\/\/support.wewalk.io\/it\/author\/ece\/"},"doc_category_info":[{"term_name":"Preferenze","term_url":"https:\/\/support.wewalk.io\/it\/art-cat\/preferenze\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Personalizzazione dell\u2019App per Utenti Ipovedenti - WeWalk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/support.wewalk.io\/it\/article\/personalizzazione-dellapp-per-utenti-ipovedenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Personalizzazione dell\u2019App per Utenti Ipovedenti - WeWalk\" \/>\n<meta property=\"og:description\" content=\"L\u2019app WeWALK \u00e8 progettata sia per persone ipovedenti sia per persone non vedenti. Per questo motivo, l\u2019app consente di modificare le impostazioni visive per migliorare l\u2019accessibilit\u00e0. Seguire i passaggi seguenti per personalizzare l\u2019app in base alle esigenze degli utenti ipovedenti: 1. Aprire la sezione \u201cIl Mio Account\u201d \u2013 Toccare il pulsante \u201cIl Mio Account\u201d, situato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/support.wewalk.io\/it\/article\/personalizzazione-dellapp-per-utenti-ipovedenti\/\" \/>\n<meta property=\"og:site_name\" content=\"WeWalk\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-10T16:15:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/article\\\/personalizzazione-dellapp-per-utenti-ipovedenti\\\/\",\"url\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/article\\\/personalizzazione-dellapp-per-utenti-ipovedenti\\\/\",\"name\":\"Personalizzazione dell\u2019App per Utenti Ipovedenti - WeWalk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/#website\"},\"datePublished\":\"2024-04-25T17:30:00+00:00\",\"dateModified\":\"2026-06-10T16:15:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/article\\\/personalizzazione-dellapp-per-utenti-ipovedenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/support.wewalk.io\\\/it\\\/article\\\/personalizzazione-dellapp-per-utenti-ipovedenti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/article\\\/personalizzazione-dellapp-per-utenti-ipovedenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articoli\",\"item\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/docs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Personalizzazione dell\u2019App per Utenti Ipovedenti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/\",\"name\":\"WeWalk\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/support.wewalk.io\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Personalizzazione dell\u2019App per Utenti Ipovedenti - WeWalk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/support.wewalk.io\/it\/article\/personalizzazione-dellapp-per-utenti-ipovedenti\/","og_locale":"it_IT","og_type":"article","og_title":"Personalizzazione dell\u2019App per Utenti Ipovedenti - WeWalk","og_description":"L\u2019app WeWALK \u00e8 progettata sia per persone ipovedenti sia per persone non vedenti. Per questo motivo, l\u2019app consente di modificare le impostazioni visive per migliorare l\u2019accessibilit\u00e0. Seguire i passaggi seguenti per personalizzare l\u2019app in base alle esigenze degli utenti ipovedenti: 1. Aprire la sezione \u201cIl Mio Account\u201d \u2013 Toccare il pulsante \u201cIl Mio Account\u201d, situato [&hellip;]","og_url":"https:\/\/support.wewalk.io\/it\/article\/personalizzazione-dellapp-per-utenti-ipovedenti\/","og_site_name":"WeWalk","article_modified_time":"2026-06-10T16:15:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/support.wewalk.io\/it\/article\/personalizzazione-dellapp-per-utenti-ipovedenti\/","url":"https:\/\/support.wewalk.io\/it\/article\/personalizzazione-dellapp-per-utenti-ipovedenti\/","name":"Personalizzazione dell\u2019App per Utenti Ipovedenti - WeWalk","isPartOf":{"@id":"https:\/\/support.wewalk.io\/it\/#website"},"datePublished":"2024-04-25T17:30:00+00:00","dateModified":"2026-06-10T16:15:57+00:00","breadcrumb":{"@id":"https:\/\/support.wewalk.io\/it\/article\/personalizzazione-dellapp-per-utenti-ipovedenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/support.wewalk.io\/it\/article\/personalizzazione-dellapp-per-utenti-ipovedenti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/support.wewalk.io\/it\/article\/personalizzazione-dellapp-per-utenti-ipovedenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/support.wewalk.io\/it\/"},{"@type":"ListItem","position":2,"name":"Articoli","item":"https:\/\/support.wewalk.io\/it\/docs\/"},{"@type":"ListItem","position":3,"name":"Personalizzazione dell\u2019App per Utenti Ipovedenti"}]},{"@type":"WebSite","@id":"https:\/\/support.wewalk.io\/it\/#website","url":"https:\/\/support.wewalk.io\/it\/","name":"WeWalk","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/support.wewalk.io\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/docs\/2789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/comments?post=2789"}],"version-history":[{"count":1,"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/docs\/2789\/revisions"}],"predecessor-version":[{"id":2790,"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/docs\/2789\/revisions\/2790"}],"wp:attachment":[{"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/media?parent=2789"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/doc_category?post=2789"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/support.wewalk.io\/it\/wp-json\/wp\/v2\/doc_tag?post=2789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}